{"id":40403,"date":"2021-06-30T14:25:08","date_gmt":"2021-06-30T14:25:08","guid":{"rendered":"https:\/\/huntermeetshunter.com\/?post_type=product&#038;p=40403"},"modified":"2026-01-07T19:16:42","modified_gmt":"2026-01-07T19:16:42","slug":"four-horn-sheep","status":"publish","type":"product","link":"https:\/\/huntermeetshunter.com\/en\/produkt\/four-horn-sheep\/","title":{"rendered":"Four Horn Sheep"},"content":{"rendered":"<p>Very unique sheep, great for trophy hunters&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Very unique sheep, great for trophy hunters&#8230;<\/p>\n","protected":false},"featured_media":56037,"template":"","meta":{"_acf_changed":false,"_themeisle_gutenberg_block_has_review":false},"product_brand":[],"product_cat":[31],"product_tag":[],"class_list":{"0":"post-40403","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-verkaufen","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/huntermeetshunter.com\/en\/wp-json\/wp\/v2\/product\/40403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/huntermeetshunter.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/huntermeetshunter.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/huntermeetshunter.com\/en\/wp-json\/wp\/v2\/media\/56037"}],"wp:attachment":[{"href":"https:\/\/huntermeetshunter.com\/en\/wp-json\/wp\/v2\/media?parent=40403"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/huntermeetshunter.com\/en\/wp-json\/wp\/v2\/product_brand?post=40403"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/huntermeetshunter.com\/en\/wp-json\/wp\/v2\/product_cat?post=40403"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/huntermeetshunter.com\/en\/wp-json\/wp\/v2\/product_tag?post=40403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}