{"id":57513,"date":"2023-02-09T11:53:34","date_gmt":"2023-02-09T11:53:34","guid":{"rendered":"https:\/\/huntermeetshunter.com\/?post_type=product&#038;p=57513"},"modified":"2026-01-07T19:16:32","modified_gmt":"2026-01-07T19:16:32","slug":"racka-sheep","status":"publish","type":"product","link":"https:\/\/huntermeetshunter.com\/en\/produkt\/racka-sheep\/","title":{"rendered":"Racka Sheep"},"content":{"rendered":"<p>Very unique sheep, great for trophy hunters&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Very unique sheep, great for trophy hunters&#8230;<\/p>\n","protected":false},"featured_media":57518,"template":"","meta":{"_acf_changed":false,"_themeisle_gutenberg_block_has_review":false},"product_brand":[],"product_cat":[31],"product_tag":[],"class_list":{"0":"post-57513","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-verkaufen","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/huntermeetshunter.com\/en\/wp-json\/wp\/v2\/product\/57513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/huntermeetshunter.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/huntermeetshunter.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/huntermeetshunter.com\/en\/wp-json\/wp\/v2\/media\/57518"}],"wp:attachment":[{"href":"https:\/\/huntermeetshunter.com\/en\/wp-json\/wp\/v2\/media?parent=57513"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/huntermeetshunter.com\/en\/wp-json\/wp\/v2\/product_brand?post=57513"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/huntermeetshunter.com\/en\/wp-json\/wp\/v2\/product_cat?post=57513"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/huntermeetshunter.com\/en\/wp-json\/wp\/v2\/product_tag?post=57513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}